{"id":547,"count":130,"description":"","link":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/","name":"Fitness Clothing","slug":"fitness-clothing-en","taxonomy":"product_cat","parent":538,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fitness Clothing - Fit360<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fitness Clothing - Fit360\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Fit360\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/product-category\\\/training-equipment-en\\\/fitness-clothing-en\\\/\",\"url\":\"https:\\\/\\\/fit360.ee\\\/en\\\/product-category\\\/training-equipment-en\\\/fitness-clothing-en\\\/\",\"name\":\"Fitness Clothing - Fit360\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/product-category\\\/training-equipment-en\\\/fitness-clothing-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/product-category\\\/training-equipment-en\\\/fitness-clothing-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fit360.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Training Equipment\",\"item\":\"https:\\\/\\\/fit360.ee\\\/en\\\/product-category\\\/training-equipment-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fitness Clothing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fit360.ee\\\/en\\\/\",\"name\":\"Fit360\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fit360.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/#organization\",\"name\":\"Fit360\",\"url\":\"https:\\\/\\\/fit360.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fit360.ee\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-fit360.png\",\"contentUrl\":\"https:\\\/\\\/fit360.ee\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-fit360.png\",\"width\":180,\"height\":66,\"caption\":\"Fit360\"},\"image\":{\"@id\":\"https:\\\/\\\/fit360.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fitness Clothing - Fit360","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/","og_locale":"en_US","og_type":"article","og_title":"Fitness Clothing - Fit360","og_url":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/","og_site_name":"Fit360","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/","url":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/","name":"Fitness Clothing - Fit360","isPartOf":{"@id":"https:\/\/fit360.ee\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/fitness-clothing-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fit360.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Training Equipment","item":"https:\/\/fit360.ee\/en\/product-category\/training-equipment-en\/"},{"@type":"ListItem","position":3,"name":"Fitness Clothing"}]},{"@type":"WebSite","@id":"https:\/\/fit360.ee\/en\/#website","url":"https:\/\/fit360.ee\/en\/","name":"Fit360","description":"","publisher":{"@id":"https:\/\/fit360.ee\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fit360.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fit360.ee\/en\/#organization","name":"Fit360","url":"https:\/\/fit360.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fit360.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fit360.ee\/wp-content\/uploads\/2017\/01\/logo-fit360.png","contentUrl":"https:\/\/fit360.ee\/wp-content\/uploads\/2017\/01\/logo-fit360.png","width":180,"height":66,"caption":"Fit360"},"image":{"@id":"https:\/\/fit360.ee\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fit360.ee\/en\/wp-json\/wp\/v2\/product_cat\/547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fit360.ee\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/fit360.ee\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/fit360.ee\/en\/wp-json\/wp\/v2\/product_cat\/538"}],"wp:post_type":[{"href":"https:\/\/fit360.ee\/en\/wp-json\/wp\/v2\/product?product_cat=547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}